{"id":3004,"date":"2020-08-04T12:23:14","date_gmt":"2020-08-04T11:23:14","guid":{"rendered":"https:\/\/flaxton-meadows.local\/majoitus\/leirintaalue\/"},"modified":"2023-01-31T14:44:42","modified_gmt":"2023-01-31T14:44:42","slug":"leirintaalue","status":"publish","type":"page","link":"https:\/\/flaxtonmeadows.co.uk\/fi\/majoitus\/leirintaalue\/","title":{"rendered":"Leirint\u00e4alue"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":2957,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3004","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yorkin leirint\u00e4alue | Flaxton Meadows Eco Camping -paikat<\/title>\n<meta name=\"description\" content=\"Luonnonsuojelualueen vieress\u00e4 sijaitsevilla leirint\u00e4alueillamme voit nauttia villiel\u00e4imist\u00e4 t\u00e4htien alla. Katso saatavuus meid\u00e4n ekologinen leirint\u00e4alue l\u00e4hell\u00e4 York.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/flaxtonmeadows.co.uk\/fi\/majoitus\/leirintaalue\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yorkin leirint\u00e4alue | Flaxton Meadows Eco Camping -paikat\" \/>\n<meta property=\"og:description\" content=\"Luonnonsuojelualueen vieress\u00e4 sijaitsevilla leirint\u00e4alueillamme voit nauttia villiel\u00e4imist\u00e4 t\u00e4htien alla. Katso saatavuus meid\u00e4n ekologinen leirint\u00e4alue l\u00e4hell\u00e4 York.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flaxtonmeadows.co.uk\/fi\/majoitus\/leirintaalue\/\" \/>\n<meta property=\"og:site_name\" content=\"Flaxton Meadows\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/campingyork\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-31T14:44:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/flaxtonmeadows.co.uk\/wp-content\/uploads\/2020\/08\/flaxton-meadows-lodges2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"489\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yorkin leirint\u00e4alue | Flaxton Meadows Eco Camping -paikat","description":"Luonnonsuojelualueen vieress\u00e4 sijaitsevilla leirint\u00e4alueillamme voit nauttia villiel\u00e4imist\u00e4 t\u00e4htien alla. Katso saatavuus meid\u00e4n ekologinen leirint\u00e4alue l\u00e4hell\u00e4 York.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/flaxtonmeadows.co.uk\/fi\/majoitus\/leirintaalue\/","og_locale":"fi_FI","og_type":"article","og_title":"Yorkin leirint\u00e4alue | Flaxton Meadows Eco Camping -paikat","og_description":"Luonnonsuojelualueen vieress\u00e4 sijaitsevilla leirint\u00e4alueillamme voit nauttia villiel\u00e4imist\u00e4 t\u00e4htien alla. Katso saatavuus meid\u00e4n ekologinen leirint\u00e4alue l\u00e4hell\u00e4 York.","og_url":"https:\/\/flaxtonmeadows.co.uk\/fi\/majoitus\/leirintaalue\/","og_site_name":"Flaxton Meadows","article_publisher":"https:\/\/www.facebook.com\/campingyork","article_modified_time":"2023-01-31T14:44:42+00:00","og_image":[{"width":960,"height":489,"url":"https:\/\/flaxtonmeadows.co.uk\/wp-content\/uploads\/2020\/08\/flaxton-meadows-lodges2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/flaxtonmeadows.co.uk\/fi\/majoitus\/leirintaalue\/","url":"https:\/\/flaxtonmeadows.co.uk\/fi\/majoitus\/leirintaalue\/","name":"Yorkin leirint\u00e4alue | Flaxton Meadows Eco Camping -paikat","isPartOf":{"@id":"https:\/\/flaxtonmeadows.co.uk\/fi\/#website"},"datePublished":"2020-08-04T11:23:14+00:00","dateModified":"2023-01-31T14:44:42+00:00","description":"Luonnonsuojelualueen vieress\u00e4 sijaitsevilla leirint\u00e4alueillamme voit nauttia villiel\u00e4imist\u00e4 t\u00e4htien alla. Katso saatavuus meid\u00e4n ekologinen leirint\u00e4alue l\u00e4hell\u00e4 York.","breadcrumb":{"@id":"https:\/\/flaxtonmeadows.co.uk\/fi\/majoitus\/leirintaalue\/#breadcrumb"},"inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/flaxtonmeadows.co.uk\/fi\/majoitus\/leirintaalue\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/flaxtonmeadows.co.uk\/fi\/majoitus\/leirintaalue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/flaxtonmeadows.co.uk\/fi\/"},{"@type":"ListItem","position":2,"name":"Majoitus","item":"https:\/\/flaxtonmeadows.co.uk\/fi\/majoitus\/"},{"@type":"ListItem","position":3,"name":"Leirint\u00e4alue"}]},{"@type":"WebSite","@id":"https:\/\/flaxtonmeadows.co.uk\/fi\/#website","url":"https:\/\/flaxtonmeadows.co.uk\/fi\/","name":"Flaxton Meadows","description":"","publisher":{"@id":"https:\/\/flaxtonmeadows.co.uk\/fi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flaxtonmeadows.co.uk\/fi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"},{"@type":"Organization","@id":"https:\/\/flaxtonmeadows.co.uk\/fi\/#organization","name":"Flaxton Meadows","url":"https:\/\/flaxtonmeadows.co.uk\/fi\/","logo":{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/flaxtonmeadows.co.uk\/fi\/#\/schema\/logo\/image\/","url":"https:\/\/flaxtonmeadows.co.uk\/wp-content\/uploads\/2020\/08\/flaxton-meadows-logo.png","contentUrl":"https:\/\/flaxtonmeadows.co.uk\/wp-content\/uploads\/2020\/08\/flaxton-meadows-logo.png","width":200,"height":265,"caption":"Flaxton Meadows"},"image":{"@id":"https:\/\/flaxtonmeadows.co.uk\/fi\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/campingyork"]}]}},"_links":{"self":[{"href":"https:\/\/flaxtonmeadows.co.uk\/fi\/wp-json\/wp\/v2\/pages\/3004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flaxtonmeadows.co.uk\/fi\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/flaxtonmeadows.co.uk\/fi\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/flaxtonmeadows.co.uk\/fi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/flaxtonmeadows.co.uk\/fi\/wp-json\/wp\/v2\/comments?post=3004"}],"version-history":[{"count":0,"href":"https:\/\/flaxtonmeadows.co.uk\/fi\/wp-json\/wp\/v2\/pages\/3004\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/flaxtonmeadows.co.uk\/fi\/wp-json\/wp\/v2\/pages\/2957"}],"wp:attachment":[{"href":"https:\/\/flaxtonmeadows.co.uk\/fi\/wp-json\/wp\/v2\/media?parent=3004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}